{"id":6192,"date":"2020-03-23T15:29:39","date_gmt":"2020-03-23T14:29:39","guid":{"rendered":"https:\/\/www.amantis.net\/blog\/?p=6192"},"modified":"2025-04-24T16:32:08","modified_gmt":"2025-04-24T14:32:08","slug":"sextories-nos-interesa-hablar-de-sexualidad-diversa-e-inclusiva","status":"publish","type":"post","link":"https:\/\/www.amantis.net\/blog\/sextories-nos-interesa-hablar-de-sexualidad-diversa-e-inclusiva\/","title":{"rendered":"Sextories: \u00abnos interesa hablar de sexualidad diversa e inclusiva\u00bb"},"content":{"rendered":"\n<p>En pleno confinamiento sacamos del caj\u00f3n una entrevista que hace unas semanas ten\u00edamos pendiente de editar. La que le hicimos al equipo de <strong><a href=\"https:\/\/sextories.net\/\" title=\"\">Sextories<\/a>: <\/strong>Roc\u00edo Vidal, coordinadora de comunicaci\u00f3n y dibujante; <a href=\"https:\/\/x.com\/toni_batres\" title=\"\">Antonio Guardiola<\/a>, director de <strong>Sextories<\/strong> y dibujante; y a <a href=\"https:\/\/x.com\/baralust\" title=\"\">Chemi Baralust<\/a>, dibujante y coordinador web. <br><br><strong><a href=\"https:\/\/www.amantis.net\/sextories-historias-cortas-chicha\/\" title=\"\">Sextories<\/a><\/strong>, para aquellos que nunca hab\u00edais o\u00eddo hablar del proyecto es un c\u00f3mic er\u00f3tico inclusivo que habla, muestra y narra sobre sexualidades diversas. Un referente en el mundo de la <strong>cultura y el erotismo. <\/strong><\/p>\n\n\n\n<p><strong>amantis: \u00bfC\u00f3mo nace Sextories?<\/strong><br><br><strong>Roc\u00edo:<\/strong> de la necesidad de hablar de la sexualidad de una manera distinta ya que el <strong>c\u00f3mic er\u00f3tico<\/strong> hasta el momento siempre hab\u00eda estado dirigido a un p\u00fablico <em>mainstream<\/em>: hombres cis heteros con fantas\u00edas determinadas. No demonizamos a este p\u00fablico, pero no creemos que sea la \u00fanica manera de concebir la sexualidad.<br><strong>Antonio:<\/strong> Nos interesa hablar de otra cosa. De diversidad y de inclusividad.<br><strong>R: <\/strong>De que toda la sexualidad es v\u00e1lida y Sextories es una celebraci\u00f3n de esa diversidad sexual y esa manera de disfrutarla y concebirla.<\/p>\n\n\n\n<p><strong>a: \u00bfSextories naci\u00f3 ya como la revista que es ahora?<\/strong><br><br><strong>A: <\/strong>Empezamos en el a\u00f1o 2012, como un <em>fanzine<\/em> de unas 90 p\u00e1ginas y con un equipo diferente, algunxs de lxs que ya no est\u00e1. <br><strong>R:<\/strong> Evolucionamos con el tiempo, el p\u00fablico cada vez nos validadaba m\u00e1s, y por lo tanto en 2017, iniciamos Sextories como el proyecto editorial independiente que es ahora. Establecida la revista ya en el circuito editorial, sigue siendo independiente, pero estamos compitiendo ya con editoriales peque\u00f1as, grandes y medianas. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"512\" data-attachment-id=\"6195\" data-permalink=\"https:\/\/www.amantis.net\/blog\/sextories-nos-interesa-hablar-de-sexualidad-diversa-e-inclusiva\/etpr1orxyauapfs\/\" data-orig-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/ETpr1OrXYAUApFs.jpeg\" data-orig-size=\"1024,512\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ETpr1OrXYAUApFs\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/ETpr1OrXYAUApFs-300x150.jpeg\" data-large-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/ETpr1OrXYAUApFs.jpeg\" src=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/ETpr1OrXYAUApFs.jpeg\" alt=\"C\u00f3mic Sextories\" class=\"wp-image-6195\" srcset=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/ETpr1OrXYAUApFs.jpeg 1024w, https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/ETpr1OrXYAUApFs-300x150.jpeg 300w, https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/ETpr1OrXYAUApFs-768x384.jpeg 768w, https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/ETpr1OrXYAUApFs-945x473.jpeg 945w, https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/ETpr1OrXYAUApFs-600x300.jpeg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>a: \u00bfQu\u00e9 veremos si leemos Sextories?<\/strong><br><br><strong>A:<\/strong> la definici\u00f3n es una caja de galletas de un mont\u00f3n de sabores. Se van a encontrar de todo. Van a ver cosas que probablemente no les atraigan visualmente, pero con contenido. Y el sexo es un medio para contar una historia. El sexo no es meramente expositivo sino que utilizamos el sexo como medio para contar historias y no como excusa.<br><strong>R:<\/strong> Normalmente cada revista tiene entre 10 y 12 historias autoconclusivas con diferente estilo, intencionalidad y manera de hablar de la sexualidad.<\/p>\n\n\n\n<p><strong>a: \u00bfQu\u00e9 dibujantes colaboran?<\/strong><br><br><strong>R:<\/strong> la portada del n\u00famero 4, es un chico trans llamado <a href=\"https:\/\/www.instagram.com\/luccer_art\/?hl=es\" title=\"\">Luc Cerver\u00f3n<\/a>, que est\u00e1 muy implicado en la divulgaci\u00f3n de p\u00edldoras de informaci\u00f3n sexol\u00f3gica y de g\u00e9nero. Es para nosotros un artista que respira Sextories. Est\u00e1 <a href=\"https:\/\/www.instagram.com\/kaoxita_art\/\" title=\"\">Kaoxita<\/a>, que habla de Shibari. Y <a href=\"https:\/\/www.instagram.com\/marcelmassegu\/\" title=\"\">Marcel P. Masseg\u00fa<\/a>, que habla sobre diversidad relacional, poliamor. Y <a href=\"https:\/\/www.instagram.com\/sarasoler_art\/\" title=\"\">Sara Soler<\/a>, que ha hablado de la experiencia de parejas de mujeres, una trans y una cis. Adem\u00e1s su pareja es Trans y ha hablado de su experiencia desde el punto de vista de una chica. <br><strong>Chemi:<\/strong> Yo en el n\u00famero 2 habl\u00e9 sobre fetiches como la lluvia dorada, y como se ve de cara la sociedad, concebido como algo turbio y sucio, prejuicio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"630\" data-attachment-id=\"6197\" data-permalink=\"https:\/\/www.amantis.net\/blog\/sextories-nos-interesa-hablar-de-sexualidad-diversa-e-inclusiva\/86187634_2697982320237206_219367958609133568_o-1\/\" data-orig-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/86187634_2697982320237206_219367958609133568_o-1.jpg\" data-orig-size=\"1200,630\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"86187634_2697982320237206_219367958609133568_o-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/86187634_2697982320237206_219367958609133568_o-1-300x158.jpg\" data-large-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/86187634_2697982320237206_219367958609133568_o-1-1024x538.jpg\" src=\"https:\/\/i0.wp.com\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/86187634_2697982320237206_219367958609133568_o-1.jpg?fit=676%2C355&amp;ssl=1\" alt=\"C\u00f3mic de Luc\" class=\"wp-image-6197\" srcset=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/86187634_2697982320237206_219367958609133568_o-1.jpg 1200w, https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/86187634_2697982320237206_219367958609133568_o-1-300x158.jpg 300w, https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/86187634_2697982320237206_219367958609133568_o-1-1024x538.jpg 1024w, https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/86187634_2697982320237206_219367958609133568_o-1-768x403.jpg 768w, https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/86187634_2697982320237206_219367958609133568_o-1-945x496.jpg 945w, https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/86187634_2697982320237206_219367958609133568_o-1-600x315.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p><strong>a: Ten\u00e9is muchos fans. \u00bfRealiz\u00e1is quedadas?<\/strong><br><br><strong>R: <\/strong>Hicimos una reuni\u00f3n de aniversario de Sextories para premiar a la comunidad que hemos generado de Sextories y celebrarlo con ellos. Hacemos una presentaci\u00f3n, un coloquio, alguna actuaci\u00f3n, una peque\u00f1a fiesta con varios de los puntos de Sextories: la diversi\u00f3n, el activismo y la libertad para crear un entorno seguro. Es un ambiente en el que todo el mundo viste como quiere, desde el punto de vista de identidad de g\u00e9nero, de libertad sexual&#8230;<\/p>\n\n\n\n<p><strong>a: \u00bfY ten\u00e9is pr\u00f3ximos proyectos en mente?<\/strong><br><br><strong>A: <\/strong>Nos gustar\u00eda enfocarnos a algo m\u00e1s sexualmente educativo y poder trabajar con sex\u00f3logos para sacar algo m\u00e1s,  hacer c\u00f3mics de manera educativa. Necesitamos asesores que nos digan c\u00f3mo hablar de manera educativa. Tambi\u00e9n nos encantaria traer a autores estranjeros. Publicar obras que nadie se atreve a publicar en Espa\u00f1a. Editar c\u00f3mics de otros autores.<br><strong>R:<\/strong> Tambi\u00e9n tenemos un proyecto de cara a Marzo* para hacer unas conferencias sobre sexualidad, g\u00e9nero y diversidad relacional.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>\n\n\n\n<p>*Esta entrevista se realiz\u00f3 a finales zde 2019. Consultad con Sextories la reprogramaci\u00f3n de las conferencias. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En pleno confinamiento sacamos del caj\u00f3n una entrevista que hace unas semanas ten\u00edamos pendiente de editar. La que le hicimos al equipo de Sextories: Roc\u00edo Vidal, coordinadora de comunicaci\u00f3n y dibujante; Antonio Guardiola, director de Sextories y dibujante; y a&#8230; <a class=\"more-link\" href=\"https:\/\/www.amantis.net\/blog\/sextories-nos-interesa-hablar-de-sexualidad-diversa-e-inclusiva\/\">Seguir leyendo &rarr;<\/a><\/p>\n","protected":false},"author":2,"featured_media":6196,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1217],"tags":[193,1344,1346,1316,1343,1345],"class_list":["post-6192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas","tag-comic","tag-comic-erotico","tag-cultura","tag-diversidad-sexual","tag-sextories","tag-sexualidad-inclusiva"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2020\/03\/1500x500.jpeg","_links":{"self":[{"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/posts\/6192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/comments?post=6192"}],"version-history":[{"count":1,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/posts\/6192\/revisions"}],"predecessor-version":[{"id":13358,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/posts\/6192\/revisions\/13358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/media\/6196"}],"wp:attachment":[{"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/media?parent=6192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/categories?post=6192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/tags?post=6192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}