{"id":257,"date":"2013-09-04T12:43:25","date_gmt":"2013-09-04T10:43:25","guid":{"rendered":"http:\/\/amantisnet.wordpress.com\/?p=257"},"modified":"2025-03-12T22:08:29","modified_gmt":"2025-03-12T21:08:29","slug":"revistas-eroticoporno-el-fin-de-una-era","status":"publish","type":"post","link":"https:\/\/www.amantis.net\/blog\/revistas-eroticoporno-el-fin-de-una-era\/","title":{"rendered":"Revistas er\u00f3ticoporno: \u00bfel fin de una era?"},"content":{"rendered":"<p>La historia cuenta que en Francia se publicaron las primeras revistas er\u00f3ticas a finales del siglo XIX. Pero su masificaci\u00f3n solo suceder\u00eda en los a\u00f1os sesenta, en Espa\u00f1a un poco m\u00e1s tarde gracias a nuestro Paco, cuando empezaron a editarse revistas con contenidos totalmente \u2018exxxpl\u00edcitos\u2019.<\/p>\n<p><a href=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/60.jpg\"><img decoding=\"async\" data-attachment-id=\"258\" data-permalink=\"https:\/\/www.amantis.net\/blog\/revistas-eroticoporno-el-fin-de-una-era\/attachment\/60\/\" data-orig-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/60.jpg\" data-orig-size=\"660,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"60\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/60-248x300.jpg\" data-large-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/60.jpg\" class=\"aligncenter wp-image-258 size-full\" src=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/60.jpg\" alt=\"portadas de revistas er\u00f3ticas\" width=\"660\" height=\"800\" srcset=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/60.jpg 660w, https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/60-248x300.jpg 248w, https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/60-600x727.jpg 600w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><\/a><\/p>\n<p><strong>Las revistas reinas<\/strong><br \/><a href=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/playboy-portada-72.jpg\"><img decoding=\"async\" data-attachment-id=\"259\" data-permalink=\"https:\/\/www.amantis.net\/blog\/revistas-eroticoporno-el-fin-de-una-era\/playboy-portada-72\/\" data-orig-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/playboy-portada-72.jpg\" data-orig-size=\"264,349\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Playboy-portada-72\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/playboy-portada-72-227x300.jpg\" data-large-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/playboy-portada-72.jpg\" class=\"alignleft wp-image-259 size-full\" src=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/playboy-portada-72.jpg\" alt=\"portada revista playboy 007\" width=\"264\" height=\"349\" srcset=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/playboy-portada-72.jpg 264w, https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/playboy-portada-72-227x300.jpg 227w\" sizes=\"(max-width: 264px) 100vw, 264px\" \/><\/a>Y <a title=\"Wikipedia: revista PlayBoy\" href=\"https:\/\/es.wikipedia.org\/wiki\/Playboy\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Playboy<\/strong><\/a> es la <em>number one.<\/em> Fundada en Chicago, Illinois en 1953 por <a title=\"Wikipedia: qui\u00e9n es Hugh Hefner\" href=\"https:\/\/es.wikipedia.org\/wiki\/Hugh_Hefner\" target=\"_blank\" rel=\"noopener noreferrer\">Hugh Hefner<\/a>, la revista se publica mensualmente, m\u00e1s all\u00e1 de las t\u00edpicas fotos tambi\u00e9n ofrece entrevistas con figuras p\u00fablicas. Adem\u00e1s de una oda a lo er\u00f3tico, la revista a trav\u00e9s de su historia ha demostrado ser un icono de la libertad, con ediciones pol\u00edticas y sociales.<br \/>Su principal rival es <a title=\"Wikipedia: la revista Penthouse (en ingl\u00e9s)\" href=\"https:\/\/en.wikipedia.org\/wiki\/Penthouse_(magazine)\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Penthouse<\/strong><\/a>. Revista masculina fundada por <a title=\"Qui\u00e9n es Bob Guccione, Wikipedia, en ingl\u00e9s\" href=\"https:\/\/en.wikipedia.org\/wiki\/Bob_Guccione\" target=\"_blank\" rel=\"noopener noreferrer\">Bob Guccione<\/a> , empez\u00f3 mezclando art\u00edculos sobre estilo de vida urbano con reportajes fotogr\u00e1ficos de pornograf\u00eda suave, pero en los a\u00f1os 90 acab\u00f3 pas\u00e1ndose al porno duro.<\/p>\n<p><strong>Las revistas espa\u00f1olas m\u00e1s calientes<\/strong><\/p>\n<p data-wp-editing=\"1\"><a href=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/marisol-interviu.jpg\"><img decoding=\"async\" data-attachment-id=\"260\" data-permalink=\"https:\/\/www.amantis.net\/blog\/revistas-eroticoporno-el-fin-de-una-era\/marisol-interviu\/\" data-orig-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/marisol-interviu.jpg\" data-orig-size=\"400,520\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"marisol-interviu\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/marisol-interviu-231x300.jpg\" data-large-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/marisol-interviu.jpg\" class=\"size-full wp-image-260 alignright\" src=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/marisol-interviu.jpg\" alt=\"marisol-interviu\" width=\"400\" height=\"520\" srcset=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/marisol-interviu.jpg 400w, https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/marisol-interviu-231x300.jpg 231w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><br \/><a title=\"Web de Intervi\u00fa\" href=\"https:\/\/www.interviu.es\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Intervi\u00fa<\/strong> <\/a>naci\u00f3 en 1976 de la mano de <a title=\"Wikipedia: qui\u00e9n fue Antonio Asensio\" href=\"https:\/\/es.wikipedia.org\/wiki\/Antonio_Asensio\" target=\"_blank\" rel=\"noopener noreferrer\">Antonio Asensio<\/a>. Pero su logro no fue liderar el destape, que ya hab\u00eda sido todo un \u00e9xito con las pel\u00edculas de <a title=\"Wikipedia: qui\u00e9n es Andr\u00e9s Pajares\" href=\"https:\/\/es.wikipedia.org\/wiki\/Andr\u00e9s_Pajares\" target=\"_blank\" rel=\"noopener noreferrer\">Andr\u00e9s Pajares<\/a>, sino el revolucionar el periodismo estatal con art\u00edculos de inter\u00e9s humano, esc\u00e1ndalo p\u00fablico o pol\u00edtico o primicias de las buenas. Pero es que adem\u00e1s, fue la primera que exhibi\u00f3 mujeres en <em>topless<\/em>. Famosas nacionales y extranjeras, tetas en el aire, dieron al traste con toda la doctrina puritana del Franquismo. <a title=\"Wikipedia: qui\u00e9n es Pepa Flores\" href=\"https:\/\/es.wikipedia.org\/wiki\/Marisol_(cantante)\" target=\"_blank\" rel=\"noopener noreferrer\">Pepa Flores, nuestra querida Marisol<\/a>, la primera. Otra cosa es lo que se vende hoy, que dudamos nosotros de que las tetas de las tronistas de la tele, sean del mismo valor incalculable&#8230;<br \/>En un segundo plano quedar\u00eda <a title=\"Revista Primera L\u00ednea online\" href=\"http:\/\/www.primeralinea.es\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Primera L\u00ednea<\/strong><\/a>. Una revista de estilo de vida masculino, d\u00f3nde adem\u00e1s, tambi\u00e9n hay noticias y sesiones fotogr\u00e1ficas er\u00f3ticas. Nada del otro mundo, pero disponible en quioscos.<br \/>Menci\u00f3n aparte merece<a title=\"Tienda de Kiss Comix\" href=\"https:\/\/www.lacupula.com\/tag\/kiss-comix\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong> Kiss Comix.<\/strong><\/a> De periodicidad mensual, fue publicada por Ediciones La C\u00fapula desde 1991 hasta 2011, y se puede comprar a\u00fan hoy en su p\u00e1gina web. Referencia para muchos adolescentes, en su web tambi\u00e9n encontrar\u00e1s c\u00f3mics, novelas gr\u00e1ficas y <em>hentai<\/em>, as\u00ed como una revista er\u00f3tica en franc\u00e9s (La Poudre aux R\u00eaves), otra en ingl\u00e9s (French Kiss Comix, que se dej\u00f3 de editar en 2011) o una para homesexuales (Claro que s\u00ed, con una \u00faltima publicaci\u00f3n en 2005).<br \/>Y aunque sea m\u00e1s un c\u00f3mic que una revista, nos mola (o mol\u00f3) mucho <a title=\"Wikipedia: qu\u00e9 fue El V\u00edbora\" href=\"https:\/\/es.wikipedia.org\/wiki\/El_V\u00edbora\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>El V\u00edbora<\/strong><\/a>. Naci\u00f3 bajo el aura de c\u00f3mic <em>underground<\/em> el \u00faltimo mes de 1979 y muri\u00f3 hace pocos a\u00f1itos, en 2005, despu\u00e9s de haberse publicado m\u00e1s de 300 ejemplares y diversos especiales. Sus pap\u00e1s eran autores como Nazario, autor del primer detective transvestido Anarcoma, u otros como Max, Gallardo y Mediavilla, Alfredo Pons o Mart\u00ed y Sento. El V\u00edbora no solo era er\u00f3tica. Tambi\u00e9n recog\u00eda humor negro y la mejor de las cr\u00edticas a la sociedad. Se recuerda de ella el n\u00famero especial dedicado al 23-F, d\u00f3nde fue una de las publicaciones m\u00e1s atrevidas a hablar del tema. En fin, que como ellas, ya no quedan&#8230;<\/p>\n<p data-wp-editing=\"1\"><strong>Y en Am\u00e9rica Latina, unos <em>cracks<\/em><\/strong><br \/><a href=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/orgia.jpg\"><img decoding=\"async\" data-attachment-id=\"261\" data-permalink=\"https:\/\/www.amantis.net\/blog\/revistas-eroticoporno-el-fin-de-una-era\/orgia\/\" data-orig-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/orgia.jpg\" data-orig-size=\"550,412\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"orgia\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/orgia-300x225.jpg\" data-large-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/orgia.jpg\" class=\"alignleft wp-image-261 \" src=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/orgia.jpg\" alt=\"portada revista orgia\" width=\"316\" height=\"237\" srcset=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/orgia.jpg 550w, https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/orgia-300x225.jpg 300w\" sizes=\"(max-width: 316px) 100vw, 316px\" \/><\/a><br \/>Nuestros vecinos al otro lado del charco tambi\u00e9n son unos cr\u00e1pulas en lo que a revistillas se refiere. Hubo un tiempo en que empezaron a salir revistas pornogr\u00e1ficas hasta por gusto. En Per\u00fa se recuerda con ganas la <strong>revista Cosquillas<\/strong>\u00a0y la <strong>revista\u00a0Org\u00eda<\/strong>. Estas revistas viv\u00edan de parodias en las cuales, por ejemplo, en lugar de \u201cEl Llanero Solitario\u201d pon\u00eda \u201cEl Pajero Solitario\u201d y en lugar de \u201cAsterix\u201d, \u201cCacherix\u201d y se dibujaban las figuras de Asterix, igualitas, pero con una historia porno. \u00a1Y la gente lo compraba!<\/p>\n<p>\u00bfY t\u00fa? \u00bfConoces m\u00e1s revistas que nos quieras comentar? Cu\u00e9ntanoslo. D\u00e9janos un comentario.<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La historia cuenta que en Francia se publicaron las primeras revistas er\u00f3ticas a finales del siglo XIX. Pero su masificaci\u00f3n solo suceder\u00eda en los a\u00f1os sesenta, en Espa\u00f1a un poco m\u00e1s tarde gracias a nuestro Paco, cuando empezaron a editarse&#8230; <a class=\"more-link\" href=\"https:\/\/www.amantis.net\/blog\/revistas-eroticoporno-el-fin-de-una-era\/\">Seguir leyendo &rarr;<\/a><\/p>\n","protected":false},"author":2,"featured_media":13054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1219],"tags":[193,279,377,396,571,612,800,835,852,864,898,956],"class_list":["post-257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-comic","tag-cosquillas","tag-el-vibora","tag-erotico","tag-interviu","tag-kiss-comix","tag-orgia","tag-penthouse","tag-playboy","tag-porno","tag-primera-linea","tag-revista"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/09\/revistas-eroticas-sexuales.jpg","_links":{"self":[{"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/posts\/257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/comments?post=257"}],"version-history":[{"count":3,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/posts\/257\/revisions"}],"predecessor-version":[{"id":13055,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/posts\/257\/revisions\/13055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/media\/13054"}],"wp:attachment":[{"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/media?parent=257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/categories?post=257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/tags?post=257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}