{"id":122,"date":"2013-02-26T14:40:20","date_gmt":"2013-02-26T14:40:20","guid":{"rendered":"http:\/\/amantisnet.wordpress.com\/?p=122"},"modified":"2025-04-17T09:13:50","modified_gmt":"2025-04-17T07:13:50","slug":"padres-e-hijos-y-el-sexo-ir-juntos-de-tienda-erotica","status":"publish","type":"post","link":"https:\/\/www.amantis.net\/blog\/padres-e-hijos-y-el-sexo-ir-juntos-de-tienda-erotica\/","title":{"rendered":"Padres e hijos y el sexo: \u00bfir juntos de tienda er\u00f3tica?"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><a href=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/02\/seattle_storefront-1.jpg\"><img decoding=\"async\" width=\"205\" height=\"155\" data-attachment-id=\"123\" data-permalink=\"https:\/\/www.amantis.net\/blog\/padres-e-hijos-y-el-sexo-ir-juntos-de-tienda-erotica\/seattle_storefront-1\/\" data-orig-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/02\/seattle_storefront-1.jpg\" data-orig-size=\"205,155\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"seattle_storefront-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/02\/seattle_storefront-1.jpg\" data-large-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/02\/seattle_storefront-1.jpg\" src=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/02\/seattle_storefront-1.jpg?w=150\" alt=\"tienda sexshop\" class=\"wp-image-123\"\/><\/a><\/figure><\/div>\n\n\n<p>Hubo un tiempo, remoto y seguramente l\u00fagubre, en que la iniciaci\u00f3n a la edad adulta por parte de los hombres era pasar por un prost\u00edbulo. Los padres acompa\u00f1aban a los adolescentes a las casas de se\u00f1oritas y tras un golpecito en la espalda, lanzaban al muchacho a manos de la madame. De las chicas y anta\u00f1o no hablaremos, todos sabemos que al menos en la teor\u00eda, la cosa no se estilaba hasta el matrimonio.<\/p>\n\n\n\n<p>Por suerte, ya no es necesario que los padres busquen sexo a sus hijos. Estos ya salen suficientemente espabilados como para encontrar rollo por si solitos.<\/p>\n\n\n\n<p>Pero eso no quita que desde la familia haya una buena educaci\u00f3n sexual: que se hable de ello abiertamente, que no se reh\u00fayan las preguntas, y que se hable tan pronto como el ni\u00f1o lo pida. Hablar de ello es importante: pero hay que hacerlo con naturalidad. De igual manera que no hay que esconderse en el armario o ponerse rojo como un tomate cuando el ni\u00f1o pregunta: <em><strong>\u201c\u00bfqu\u00e9 es hacer un franc\u00e9s?\u201d<\/strong><\/em> Igual de importante es no hacer pasar verg\u00fcenza al adolescente con la t\u00edpica charla madre-padre-hijo a los 20 a\u00f1os que el adolescente ya no tiene ganas de escuchar. Hace 10 a\u00f1os que necesitaba saber. Pero a sus 20 retacos seguramente ya podr\u00e1 contarte cosas a ti.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright\"><a href=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/01\/tiendachueca.jpg\"><img decoding=\"async\" width=\"200\" height=\"267\" data-attachment-id=\"80\" data-permalink=\"https:\/\/www.amantis.net\/blog\/quienes-fuimos-quienes-somos-y-quienes-queremos-ser\/tiendachueca\/\" data-orig-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/01\/tiendachueca.jpg\" data-orig-size=\"200,267\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"tiendachueca\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/01\/tiendachueca.jpg\" data-large-file=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/01\/tiendachueca.jpg\" src=\"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/01\/tiendachueca.jpg?w=112\" alt=\"tienda amantis en chueca\" class=\"wp-image-80\"\/><\/a><\/figure><\/div>\n\n\n<p>Es necesario que el sexo sea un tema m\u00e1s: no quitar una escena er\u00f3tica de la televisi\u00f3n cuando sucede, hablar de sexo sin cortarse, de la relaci\u00f3n entre sexualidad y emociones. Cuando sea preciso y cuando el momento se preste. \u00bfY por qu\u00e9 no? Podemos dar un paso m\u00e1s: se puede entrar a una tienda er\u00f3tica igual que se fisgonea en una tienda de ropa o de coches.<\/p>\n\n\n\n<p><br>Las tiendas de juguetes er\u00f3ticos, y entre ellos las de amantis, cada d\u00eda lo ponen m\u00e1s f\u00e1cil: ya no son lo que eran. D\u00f3nde hubo un tugurio l\u00fagubre atendido por un se\u00f1or maquiav\u00e9lico hoy hay una tienda luminosa, simp\u00e1tica y atendida indistintamente por hombres y mujeres. Ya son as\u00ed muchos: en EUA es conocido <a href=\"https:\/\/www.babeland.com\/\" target=\"_blank\" rel=\"noopener\" title=\"Babeland, tienda er\u00f3tica de EUA\">Babeland<\/a>, por ser una tienda llena de colores, con m\u00fasica divertida dentro y hasta con cambiador de beb\u00e9s para que las parejas j\u00f3venes puedan acercarse; o en Espa\u00f1a tenemos amantis: dos tiendas c\u00e9ntricas en Madrid, coloridas y atendidas por gente joven, experta y <em>cool<\/em>. \u00bfA\u00fan no nos ha visitado? \u00a1Ven a vernos! Seguro que, padres e hijos, encontr\u00e1is de qu\u00e9 hablar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hubo un tiempo, remoto y seguramente l\u00fagubre, en que la iniciaci\u00f3n a la edad adulta por parte de los hombres era pasar por un prost\u00edbulo. Los padres acompa\u00f1aban a los adolescentes a las casas de se\u00f1oritas y tras un golpecito&#8230; <a class=\"more-link\" href=\"https:\/\/www.amantis.net\/blog\/padres-e-hijos-y-el-sexo-ir-juntos-de-tienda-erotica\/\">Seguir leyendo &rarr;<\/a><\/p>\n","protected":false},"author":2,"featured_media":13066,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1241],"tags":[56,132,537,600,810],"class_list":["post-122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consultorio-sexual","tag-amantis","tag-babeland","tag-hijos","tag-jugueteria-erotica","tag-padres"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/www.amantis.net\/blog\/wp-content\/uploads\/2013\/02\/sexshop-padres-e-hijos.jpg","_links":{"self":[{"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/posts\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/comments?post=122"}],"version-history":[{"count":1,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/posts\/122\/revisions"}],"predecessor-version":[{"id":13068,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/posts\/122\/revisions\/13068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/media\/13066"}],"wp:attachment":[{"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/media?parent=122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/categories?post=122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amantis.net\/blog\/wp-json\/wp\/v2\/tags?post=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}